{"id":170,"date":"2020-11-18T09:22:44","date_gmt":"2020-11-18T12:22:44","guid":{"rendered":"https:\/\/lenorarosenfield.com\/?post_type=exposicoes&#038;p=170"},"modified":"2020-12-12T16:38:02","modified_gmt":"2020-12-12T19:38:02","slug":"subtracao-e-ausencia-2004-2005","status":"publish","type":"exposicoes","link":"https:\/\/lenorarosenfield.com\/en\/exposicoes\/subtracao-e-ausencia-2004-2005\/","title":{"rendered":"Subtraction and Absence, 2004\/2005"},"content":{"rendered":"<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1259\" src=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0637-1600x1259.jpeg\" alt=\"\" data-id=\"171\" data-link=\"https:\/\/lenorarosenfield.com\/?attachment_id=171\" class=\"wp-image-171\" srcset=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0637-1600x1259.jpeg 1600w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0637-800x629.jpeg 800w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0637-16x12.jpeg 16w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1163\" src=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0635-1600x1163.jpeg\" alt=\"\" data-id=\"172\" data-link=\"https:\/\/lenorarosenfield.com\/?attachment_id=172\" class=\"wp-image-172\" srcset=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0635-1600x1163.jpeg 1600w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0635-800x582.jpeg 800w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0635-16x12.jpeg 16w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1188\" src=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0636-1600x1188.jpeg\" alt=\"\" data-id=\"173\" data-link=\"https:\/\/lenorarosenfield.com\/?attachment_id=173\" class=\"wp-image-173\" srcset=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0636-1600x1188.jpeg 1600w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0636-800x594.jpeg 800w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/IMG_0636-16x12.jpeg 16w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"906\" height=\"583\" src=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite9.jpeg\" alt=\"\" data-id=\"178\" data-full-url=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite9.jpeg\" data-link=\"https:\/\/lenorarosenfield.com\/exposicoes\/subtracao-e-ausencia\/convite9\/\" class=\"wp-image-178\" srcset=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite9.jpeg 906w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite9-800x515.jpeg 800w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite9-16x10.jpeg 16w\" sizes=\"auto, (max-width: 906px) 100vw, 906px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1175\" height=\"873\" src=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite6.jpeg\" alt=\"\" data-id=\"176\" data-link=\"https:\/\/lenorarosenfield.com\/exposicoes\/subtracao-e-ausencia\/convite6\/\" class=\"wp-image-176\" srcset=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite6.jpeg 1175w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite6-800x594.jpeg 800w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite6-16x12.jpeg 16w\" sizes=\"auto, (max-width: 1175px) 100vw, 1175px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1165\" height=\"867\" src=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite5.jpeg\" alt=\"\" data-id=\"177\" data-link=\"https:\/\/lenorarosenfield.com\/exposicoes\/subtracao-e-ausencia\/convite5\/\" class=\"wp-image-177\" srcset=\"https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite5.jpeg 1165w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite5-800x595.jpeg 800w, https:\/\/lenorarosenfield.com\/wp-content\/uploads\/2020\/11\/convite5-16x12.jpeg 16w\" sizes=\"auto, (max-width: 1165px) 100vw, 1165px\" \/><\/figure><\/li><\/ul><\/figure>","protected":false},"featured_media":177,"template":"","class_list":["post-170","exposicoes","type-exposicoes","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lenorarosenfield.com\/en\/wp-json\/wp\/v2\/exposicoes\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lenorarosenfield.com\/en\/wp-json\/wp\/v2\/exposicoes"}],"about":[{"href":"https:\/\/lenorarosenfield.com\/en\/wp-json\/wp\/v2\/types\/exposicoes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lenorarosenfield.com\/en\/wp-json\/wp\/v2\/media\/177"}],"wp:attachment":[{"href":"https:\/\/lenorarosenfield.com\/en\/wp-json\/wp\/v2\/media?parent=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}